{"id":1938,"date":"2025-03-24T09:59:44","date_gmt":"2025-03-24T08:59:44","guid":{"rendered":"https:\/\/labicicletteria.sviluppo.host\/?page_id=1938"},"modified":"2025-05-15T09:42:39","modified_gmt":"2025-05-15T07:42:39","slug":"cookie-policy","status":"publish","type":"page","link":"https:\/\/www.edicolacivic.com\/index.php\/cookie-policy\/","title":{"rendered":"Cookie Policy"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La navigazione sul sito web&nbsp;<strong>edicolacivic.com<\/strong>&nbsp;(di seguito indicato anche come \u201csito web\u201d) comporta l\u2019invio di cookie e strumenti analoghi al terminale dell\u2019utente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pertanto, cos\u00ec come prescritto dagli artt. 13 e 122 del D. Lgs. 196\/2003 (\u201ccodice privacy\u201d), nonch\u00e9 in base a quanto previsto dal Provvedimento generale del Garante privacy dell\u20198 maggio 2014, Bud srl, Via Arena 9, 20123, Milano \u2013 PIVA 11314520963 titolare del trattamento, fornisce agli utenti le informazioni relative ai cookie o sistemi analoghi utilizzati o di cui si consente l\u2019installazione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cosa sono i cookie<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I cookie sono stringhe di testo di piccole dimensioni che i siti visitati dall\u2019utente inviano al suo terminale (solitamente al browser), dove vengono memorizzati per essere poi ritrasmessi agli stessi siti alla successiva visita del medesimo utente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si suddividono in cookie tecnici (utilizzati al solo fine di effettuare la trasmissione di una comunicazione su una rete di comunicazione elettronica o nella misura strettamente necessaria al fornitore di un servizio della societ\u00e0 dell\u2019informazione esplicitamente richiesto) o di profilazione (volti a creare profili relativi all\u2019utente ed utilizzati al fine di inviare messaggi pubblicitari in linea con le preferenze manifestate dallo stesso nell\u2019ambito della navigazione).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nel corso della navigazione l\u2019utente potrebbe ricevere sul suo terminale anche cookie che vengono inviati da siti o da web server diversi (c.d. cookies di \u201cterze parti\u201d), impostati direttamente da gestori di detti siti web e utilizzati per le finalit\u00e0 e secondo le modalit\u00e0 da questi definiti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Quali sono gli strumenti analoghi per cui si applica la stessa disciplina prevista per i cookie<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La disciplina relativa all\u2019uso dei cookie riguarda anche altri strumenti analoghi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si tratta di quegli strumenti (come ad esempio pixel, web beacon, web bug, clear GIF o altri) che consentono l\u2019identificazione dell\u2019utente o del terminale e che quindi sono stati ricompresi nell\u2019ambito del provvedimento del Garante Privacy dell\u20198 maggio 2014.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tipologie di cookie utilizzate dal presente sito<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il Sito utilizza cookie tecnici, nonch\u00e9 cookie analytics di terze parti e cookie e strumenti analoghi profilanti di terze parti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cookie tecnici<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il sito utilizza cookie tecnici, rispetto ai quali, ai sensi dell\u2019art. 122 del codice privacy e del Provvedimento del Garante dell\u20198 maggio 2014, non \u00e8 richiesto alcun consenso da parte dell\u2019interessato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pi\u00f9 precisamente il sito utilizza i seguenti cookie tecnici:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>NOME COOKIE<\/strong><\/td><td><strong>SCADENZA<\/strong><\/td><\/tr><tr><td>PHPSESSID&nbsp;&nbsp;&nbsp;<\/td><td>Al termine della sessione di navigazione<\/td><\/tr><tr><td>Icl_current_language(per memorizzare la lingua selezionata)<\/td><td>Al termine della sessione di navigazione<\/td><\/tr><tr><td>wordpress_logged_in_(per memorizzare le credenziali di accesso all\u2019area riservata)<\/td><td>Al termine della sessione di navigazione<\/td><\/tr><tr><td>wordpress_test_cookie<br>(WordPress imposta questo cookie quando si accede dalla pagina di login. Il cookie viene utilizzato per verificare se il browser web \u00e8 impostato per consentire o rifiutare i cookie.)<\/td><td>Al termine della sessione di navigazione<\/td><\/tr><tr><td>wordpress_xxxxx<br>(WordPress utilizza questi cookie per memorizzare i dettagli di autenticazione)<\/td><td>Al termine della sessione di navigazione<\/td><\/tr><tr><td>wp-settings-1<br>(WordPress utilizza questo cookie per personalizzare la visualizzazione dell\u2019interfaccia di amministrazione e eventualmente anche l\u2019interfaccia principale del sito.)<\/td><td>1 anno<\/td><\/tr><tr><td>wp-settings-time-1<br>(WordPress utilizza questo cookie per personalizzare la visualizzazione dell\u2019interfaccia di amministrazione e eventualmente anche l\u2019interfaccia principale del sito.)<\/td><td>1 anno<\/td><\/tr><tr><td>w3tc_referrer(per il corretto funzionamento della piattaforma)&nbsp;<\/td><td>Termina alla chiusura del browser<\/td><\/tr><tr><td>bp-activity-oldestpage&nbsp;<\/td><td>Al termine della sessione di navigazione&nbsp;<\/td><\/tr><tr><td>woocommerce_recently_viewed(Usato per creare una statistica degli oggetti dell\u2019e-commerce visitati di recente)<\/td><td>Al termine della sessione di navigazione&nbsp;<\/td><\/tr><tr><td>woocommerce_items_in_cart<br>(contiene un codice univoco per ciascun utente, cosicch\u00e9 \u00e8 possibile reperire le informazioni del carrello da un database creato per ciascun utente. Nessuna informazione di carattere personale \u00e8 memorizzata in questo cookies)<\/td><td>Al termine della sessione di navigazione&nbsp;<\/td><\/tr><tr><td>woocommerce_cart_hash(contiene un codice univoco per ciascun utente, cosicch\u00e9 \u00e8 possibile reperire le informazioni del carrello da un database creato per ciascun utente. Nessuna informazione di carattere personale \u00e8 memorizzata in questo cookies)<\/td><td>Al termine della sessione di navigazione&nbsp;<\/td><\/tr><tr><td>wp_woocommerce_session(contiene informazioni sull\u2019intero carrello ed aiutano il sistema di e-commerce a sapere quando le informazioni nel carrello cambiano. Nessuna informazione di carattere personale \u00e8 memorizzata in questo cookies)<\/td><td>Un giorno<\/td><\/tr><tr><td>cookie_notice_accepted(evita che l\u2019informativa breve contenuta nel banner ricompaia nel caso di collegamenti effettuati entro il termine di scadenza)<\/td><td>&nbsp;2 anni<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cookie di terze parti<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Attraverso il sito sono installati alcuni cookie di terze parti non tecnici, che si attivano cliccando sul tasto \u201cOK\u201d presente all\u2019interno del banner che l\u2019utente visualizza quando accede al sito web oppure proseguendo la navigazione attraverso scroll.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si riportano nel dettaglio i singoli cookie di terze parti, nonch\u00e9 i link attraverso i quali l\u2019utente pu\u00f2 ricevere maggiori informazioni e richiedere la disattivazione dei cookie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Google Analytics<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il&nbsp;Sito utilizza Google Analytics per fini di analisi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si tratta di un servizio di analisi web fornito da Google che utilizza dei cookie, che vengono depositati sul computer dell\u2019utente per consentire analisi statistiche in ordine all\u2019utilizzo del sito web visitato; si precisa inoltre che oltre i cookie, viene utilizzato da Google anche un pixel tag (<a href=\"http:\/\/www.google.it\/intl\/it\/policies\/privacy\/key-terms\/\">http:\/\/www.google.it\/intl\/it\/policies\/privacy\/key-terms\/<\/a>).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I Dati generati da Google Analytics sono conservati da Google cos\u00ec come indicato nella Informativa reperibile qui&nbsp;<a href=\"https:\/\/developers.google.com\/analytics\/devguides\/collection\/analyticsjs\/cookie-usage\">https:\/\/developers.google.com\/analytics\/devguides\/collection\/analyticsjs\/cookie-usage<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per consultare l\u2019informativa privacy della societ\u00e0 Google si rinvia al sito Internet&nbsp;<a href=\"http:\/\/www.google.com\/intl\/en\/analytics\/privacyoverview.html\">http:\/\/www.google.com\/intl\/en\/analytics\/privacyoverview.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al seguente link&nbsp;<a href=\"https:\/\/support.google.com\/analytics\/answer\/2763052?hl=it\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=it&nbsp;<\/a>&nbsp;vi \u00e8 il componente aggiuntivo del browser per la disattivazione di Google Analytics.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Widget&nbsp;<em>CookieYes | GDPR Cookie Consent &amp; Compliance Notice<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il Widget di CookieYes | GDPR Cookie Consent &amp; Compliance Notice \u00e8 un servizio di interazione con la piattaforma di supporto che comporta il rilascio di cookie non tecnici. Si riporta il link alla policy privacy della societ\u00e0 fornitrice del servizio:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Servizi di remarketing di Google<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il Sito utilizza servizi di remarketing offerti da Google Inc. che comportano l\u2019installazione di cookie e pixel utilizzati per proporre annunci maggiormente attinenti agli interessi dell\u2019utente. Tali strumenti sono utilizzati dal titolare del sito per attivit\u00e0 di remarketing.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per consultare l\u2019informativa privacy della societ\u00e0 Google e disattivazione si rinvia ai seguenti link:&nbsp;<a href=\"http:\/\/www.google.com\/intl\/it_it\/policies\/technologies\/ads\/-\">http:\/\/www.google.com\/intl\/it_it\/policies\/technologies\/ads\/-<\/a>&nbsp;<a href=\"https:\/\/www.google.it\/ads\/preferences\">https:\/\/www.google.it\/ads\/preferences<\/a>&nbsp;\u2013<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Facebook remarketing<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il sito utilizza facebook remarketing per attivit\u00e0 di remarketing.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si tratta di un servizio offerto da Facebook Inc., che comporta l\u2019installazione di cookie e pixel utilizzati per proporre annunci maggiormente attinenti agli interessi dell\u2019utente. Tali strumenti sono utilizzati dal titolare del sito per attivit\u00e0 di remarketing.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per maggiori informazioni, anche sulla disattivazione di tali cookie, si consiglia di consultare il seguente link<a href=\"https:\/\/www.facebook.com\/help\/cookies\">&nbsp;https:\/\/www.facebook.com\/help\/cookies<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Installazione dei cookie<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fatta eccezione per i cookie tecnici, l\u2019installazione degli altri cookie e strumenti analoghi \u00e8 rimessa alla volont\u00e0 dell\u2019utente che, dopo aver preso visione dell\u2019informativa breve contenuta nell\u2019apposito banner, decida di autorizzarne l\u2019installazione cliccando sul tasto \u201cOK\u201d oppure proseguendo la navigazione mediante scroll.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Disabilitazione dei cookie<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fermo restando quanto sopra indicato in ordine ai cookie tecnici necessari alla navigazione, l\u2019utente pu\u00f2 eliminare gli altri cookie attraverso le funzionalit\u00e0 indicate nella presente informativa, nella parte in cui si elencano i cookie utilizzati oppure direttamente tramite il proprio browser.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si precisa che ciascun browser presenta procedure diverse per la gestione delle impostazioni. L\u2019utente pu\u00f2 ottenere istruzioni specifiche attraverso i link sottostanti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/windows.microsoft.com\/it-it\/windows7\/block-enable-or-allow-cookies\"><strong>Microsoft Windows Explorer<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/support.google.com\/chrome\/bin\/answer.py?hl=it&amp;answer=95647&amp;p=cpn_cook\"><strong>Google Chrome&nbsp;<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/support.mozilla.org\/it-IT\/kb\/Enabling\"><strong>Mozilla Firefox&nbsp;<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/support.apple.com\/kb\/PH17191?viewlocale=it_IT&amp;locale=it_IT\"><strong>Apple Safari<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In ordine agli utenti che navigano da mobile, si precisa che le configurazioni di sistema per escludere&nbsp;l\u2019archiviazione di cookie o per cancellarli variano a seconda della&nbsp;marca e\/o del modello del device utilizzato e si rende pertanto necessario consultare le indicazioni fornite dal produttore.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per avere informazioni sui cookie archiviati sul proprio terminale e disattivarli singolarmente si rinvia al link:&nbsp;<a href=\"http:\/\/www.youronlinechoices.com\/it\/le-tue-scelte\">http:\/\/www.youronlinechoices.com\/it\/le-tue-scelte<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Diritti dell\u2019interessato<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019interessato potr\u00e0 far valere in ogni momento, senza formalit\u00e0, rivolgendosi al titolare del trattamento, anche tramite l\u2019invio di una mail all\u2019indirizzo <strong>info@edicolacivic.com<\/strong>, i diritti di cui all\u2019art. 7 del D.Lgs. 30 giugno 2003 n. 196, che di seguito si riporta testualmente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Art. 7 D. Lgs. 196\/2003<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019interessato ha diritto di ottenere la conferma dell\u2019esistenza o meno di dati personali che lo riguardano, anche se non ancora registrati, e la loro comunicazione in forma intelligibile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019interessato ha diritto di ottenere l\u2019indicazione:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">a) dell\u2019origine dei dati personali;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">b) delle finalit\u00e0 e modalit\u00e0 del trattamento;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">c) della logica applicata in caso di trattamento effettuato con l\u2019ausilio di strumenti elettronici;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">d) degli estremi identificativi del titolare, dei responsabili e del rappresentante designato ai sensi dell\u2019articolo 5, comma 2;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">e) dei soggetti o delle categorie di soggetti ai quali i dati personali possono essere comunicati o che possono venirne a conoscenza in qualit\u00e0 di rappresentante designato nel territorio dello Stato, di responsabili o incaricati.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019interessato ha diritto di ottenere:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">a) l\u2019aggiornamento, la rettificazione ovvero, quando vi ha interesse, l\u2019integrazione dei dati;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">b) la cancellazione, la trasformazione in forma anonima o il blocco dei dati trattati in violazione di legge, compresi quelli di cui non \u00e8 necessaria la conservazione in relazione agli scopi per i quali i dati sono stati raccolti o successivamente trattati;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">c) l\u2019attestazione che le operazioni di cui alle lettere a) e b) sono state portate a conoscenza, anche per quanto riguarda il loro contenuto, di coloro ai quali i dati sono stati comunicati o diffusi, eccettuato il caso in cui tale adempimento si rivela impossibile o comporta un impiego di mezzi manifestamente sproporzionato rispetto al diritto tutelato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019interessato ha diritto di opporsi, in tutto o in parte:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">a) per motivi legittimi al trattamento dei dati personali che lo riguardano, ancorch\u00e9 pertinenti allo scopo della raccolta;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">b) al trattamento di dati personali che lo riguardano a fini di invio di materiale pubblicitario o di vendita diretta o per il compimento di ricerche di mercato o di comunicazione commerciale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La navigazione sul sito web&nbsp;edicolacivic.com&nbsp;(di seguito indicato anche come \u201csito web\u201d) comporta l\u2019invio di cookie e strumenti analoghi al terminale dell\u2019utente. Pertanto, cos\u00ec come prescritto dagli artt. 13 e 122 del D. Lgs. 196\/2003 (\u201ccodice privacy\u201d), nonch\u00e9 in base a quanto previsto dal Provvedimento generale del Garante privacy dell\u20198 maggio 2014, Bud srl, Via Arena [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1938","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cookie Policy - Civic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.edicolacivic.com\/index.php\/cookie-policy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cookie Policy - Civic\" \/>\n<meta property=\"og:description\" content=\"La navigazione sul sito web&nbsp;edicolacivic.com&nbsp;(di seguito indicato anche come \u201csito web\u201d) comporta l\u2019invio di cookie e strumenti analoghi al terminale dell\u2019utente. Pertanto, cos\u00ec come prescritto dagli artt. 13 e 122 del D. Lgs. 196\/2003 (\u201ccodice privacy\u201d), nonch\u00e9 in base a quanto previsto dal Provvedimento generale del Garante privacy dell\u20198 maggio 2014, Bud srl, Via Arena [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.edicolacivic.com\/index.php\/cookie-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Civic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/civicedicola\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-15T07:42:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.edicolacivic.com\\\/index.php\\\/cookie-policy\\\/\",\"url\":\"https:\\\/\\\/www.edicolacivic.com\\\/index.php\\\/cookie-policy\\\/\",\"name\":\"Cookie Policy - Civic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.edicolacivic.com\\\/#website\"},\"datePublished\":\"2025-03-24T08:59:44+00:00\",\"dateModified\":\"2025-05-15T07:42:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.edicolacivic.com\\\/index.php\\\/cookie-policy\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.edicolacivic.com\\\/index.php\\\/cookie-policy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.edicolacivic.com\\\/index.php\\\/cookie-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.edicolacivic.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cookie Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.edicolacivic.com\\\/#website\",\"url\":\"https:\\\/\\\/www.edicolacivic.com\\\/\",\"name\":\"Edicola Civic\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.edicolacivic.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.edicolacivic.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.edicolacivic.com\\\/#organization\",\"name\":\"Edicola Civic\",\"url\":\"https:\\\/\\\/www.edicolacivic.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.edicolacivic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.edicolacivic.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Exomedia_Civic_Favicon-Green.png\",\"contentUrl\":\"https:\\\/\\\/www.edicolacivic.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Exomedia_Civic_Favicon-Green.png\",\"width\":1384,\"height\":1068,\"caption\":\"Edicola Civic\"},\"image\":{\"@id\":\"https:\\\/\\\/www.edicolacivic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/civicedicola\",\"https:\\\/\\\/www.instagram.com\\\/civic_edicola\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cookie Policy - Civic","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.edicolacivic.com\/index.php\/cookie-policy\/","og_locale":"it_IT","og_type":"article","og_title":"Cookie Policy - Civic","og_description":"La navigazione sul sito web&nbsp;edicolacivic.com&nbsp;(di seguito indicato anche come \u201csito web\u201d) comporta l\u2019invio di cookie e strumenti analoghi al terminale dell\u2019utente. Pertanto, cos\u00ec come prescritto dagli artt. 13 e 122 del D. Lgs. 196\/2003 (\u201ccodice privacy\u201d), nonch\u00e9 in base a quanto previsto dal Provvedimento generale del Garante privacy dell\u20198 maggio 2014, Bud srl, Via Arena [&hellip;]","og_url":"https:\/\/www.edicolacivic.com\/index.php\/cookie-policy\/","og_site_name":"Civic","article_publisher":"https:\/\/www.facebook.com\/civicedicola","article_modified_time":"2025-05-15T07:42:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.edicolacivic.com\/index.php\/cookie-policy\/","url":"https:\/\/www.edicolacivic.com\/index.php\/cookie-policy\/","name":"Cookie Policy - Civic","isPartOf":{"@id":"https:\/\/www.edicolacivic.com\/#website"},"datePublished":"2025-03-24T08:59:44+00:00","dateModified":"2025-05-15T07:42:39+00:00","breadcrumb":{"@id":"https:\/\/www.edicolacivic.com\/index.php\/cookie-policy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.edicolacivic.com\/index.php\/cookie-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.edicolacivic.com\/index.php\/cookie-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.edicolacivic.com\/"},{"@type":"ListItem","position":2,"name":"Cookie Policy"}]},{"@type":"WebSite","@id":"https:\/\/www.edicolacivic.com\/#website","url":"https:\/\/www.edicolacivic.com\/","name":"Edicola Civic","description":"","publisher":{"@id":"https:\/\/www.edicolacivic.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.edicolacivic.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.edicolacivic.com\/#organization","name":"Edicola Civic","url":"https:\/\/www.edicolacivic.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.edicolacivic.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.edicolacivic.com\/wp-content\/uploads\/2024\/08\/Exomedia_Civic_Favicon-Green.png","contentUrl":"https:\/\/www.edicolacivic.com\/wp-content\/uploads\/2024\/08\/Exomedia_Civic_Favicon-Green.png","width":1384,"height":1068,"caption":"Edicola Civic"},"image":{"@id":"https:\/\/www.edicolacivic.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/civicedicola","https:\/\/www.instagram.com\/civic_edicola\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.edicolacivic.com\/index.php\/wp-json\/wp\/v2\/pages\/1938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.edicolacivic.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.edicolacivic.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.edicolacivic.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.edicolacivic.com\/index.php\/wp-json\/wp\/v2\/comments?post=1938"}],"version-history":[{"count":4,"href":"https:\/\/www.edicolacivic.com\/index.php\/wp-json\/wp\/v2\/pages\/1938\/revisions"}],"predecessor-version":[{"id":3001,"href":"https:\/\/www.edicolacivic.com\/index.php\/wp-json\/wp\/v2\/pages\/1938\/revisions\/3001"}],"wp:attachment":[{"href":"https:\/\/www.edicolacivic.com\/index.php\/wp-json\/wp\/v2\/media?parent=1938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}